{"id":5591,"date":"2017-08-30T08:08:43","date_gmt":"2017-08-30T06:08:43","guid":{"rendered":"https:\/\/www.pronepal.org\/?p=5591\/"},"modified":"2017-12-07T19:07:00","modified_gmt":"2017-12-07T17:07:00","slug":"nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok","status":"publish","type":"post","link":"https:\/\/www.pronepal.org\/it\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\/","title":{"rendered":"Nuova iniziativa &#8211; Ricostruzione di una scuola a Jiri, distretto di Shindupalchok"},"content":{"rendered":"<p>Gi\u00e1 nell&#8217;autunno 2016 ProNepal ha deliberato di sostenere la ricostruzione di una scuola a Ramechap. Poich\u00e9 successivamente il governo nepalese aveva assicurato il finanziamento diretto della ricostruzione della suola ProNepal , prevvia valutazione congiunta con la nostra referente sig.ra Maya Sherpa , si \u00e9 potuto ritirare dall&#8217;iniziativa. Di consequenza la nostra referente ha individuato un altra piccola scuola in un villaggio molto remoto, dove nessun aiuto finora era \u00a0ancora giunto.<\/p>\n<p>Nel maggio 2017 ProNepal ha deciso di sostenere la scuola \u00a0<strong>Shree Sundar Devi Basic School, <\/strong>sita a\u00a0\u00a0Mankha 7, Buwase, distretto di \u00a0Shindupalchok <a href=\"https:\/\/goo.gl\/maps\/mfGJwwYyJsr\">(vedasi link sulla posizione della localit\u00e1).<\/a>\u00a0Questa mini scuola era stata fortemente danneggiata dai terremoti del 2015, e tuttora le lezioni vengono tenute in ricoveri temporanei e provvisori. N\u00e9 il governo nepalese, n\u00e9 altre \u00a0organizzazioni hanno tuttora portato aiuti di nessun tipo.<\/p>\n<p>Si tratta \u00a0di una ricostruzione della scuola, che ha 3 classi per un totale di attualmente 48 studenti, tra cui 21 femmine \u00a0e 27 maschi. Questi bambini appartengono principalmente alla communit\u00e1 Tamang.<\/p>\n<p>All&#8217;inizio ProNepal voleva sostenere la ricostruzione della scuola con un contributo di 15.000 \u20ac. Durante i primi lavori sono sorti problemi nel sottofondo della scuola. Il terremoto aveva creato una profonda buca, proprio sotto una delle aule. Il buco \u00a0non era visibile prima che venissero tolte le macerie . Questo imprevvisto ha indotto ProNepal ad aumentare il contributo a 18.000 Euro.<\/p>\n<p>Una notevole parte dei lavori sono gi\u00e1 stati iniziati nella tarda primavera. Purtroppo le forti piogge monsoniche portebbero fare slittare il termine prevvisto dei lavori.<\/p>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_gallery-9d090d6c4a5dc16947cfb94d742e2621\">\n#top .avia-gallery.av-av_gallery-9d090d6c4a5dc16947cfb94d742e2621 .avia-gallery-thumb a{\nwidth:25%;\n}\n<\/style>\n<div  class='avia-gallery av-av_gallery-9d090d6c4a5dc16947cfb94d742e2621 avia_animate_when_visible  avia-builder-el-0  avia-builder-el-no-sibling  av-hide-gallery-thumbs deactivate_avia_lazyload av-slideshow-ui av-loop-manual-endless av-control-hidden av-navigate-arrows av-navigate-dots hover-effect av-control-hidden avia-gallery-animate avia-gallery-1'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><meta itemprop=\"contentURL\" content=\"https:\/\/www.pronepal.org\/it\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\/\"><div class='avia-gallery-big-wrapper'><a class='avia-gallery-big fakeLightbox lightbox avia-gallery-big-crop-thumb ' href=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5509.jpg\" data-srcset=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5509.jpg 640w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5509-300x225.jpg 300w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5509-450x338.jpg 450w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5509-600x450.jpg 600w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5509-403x302.jpg 403w\" data-sizes=\"(max-width: 640px) 100vw, 640px\"  data-onclick='1' title='CIMG5509' ><span class='avia-gallery-big-inner'  itemprop=\"thumbnailUrl\" ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-5495 avia-img-lazy-loading-not-5495\"  width=\"640\" height=\"480\" src=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5509.jpg\" title='CIMG5509' alt='' srcset=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5509.jpg 640w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5509-300x225.jpg 300w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5509-450x338.jpg 450w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5509-600x450.jpg 600w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5509-403x302.jpg 403w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/span><\/a><\/div><div class='avia-gallery-thumb'><a href=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5509.jpg\" data-srcset=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5509.jpg 640w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5509-300x225.jpg 300w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5509-450x338.jpg 450w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5509-600x450.jpg 600w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5509-403x302.jpg 403w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" data-rel='gallery-1' data-prev-img='https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5509.jpg' class='first_thumb lightbox ' data-onclick='1' title='CIMG5509'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-5495 avia-img-lazy-loading-not-5495\"   src=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5509-495x400.jpg\" width=\"495\" height=\"400\"  title='CIMG5509' alt='' \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-5495 avia-img-lazy-loading-5495\"  width=\"640\" height=\"480\" src=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5509.jpg\" title='CIMG5509' alt='' srcset=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5509.jpg 640w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5509-300x225.jpg 300w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5509-450x338.jpg 450w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5509-600x450.jpg 600w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5509-403x302.jpg 403w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/div><\/a><a href=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1313.jpg\" data-srcset=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1313.jpg 640w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1313-300x169.jpg 300w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1313-450x253.jpg 450w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1313-600x338.jpg 600w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1313-537x302.jpg 537w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" data-rel='gallery-1' data-prev-img='https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1313.jpg' class='lightbox ' data-onclick='2' title='IMG_1313'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-5507 avia-img-lazy-loading-not-5507\"   src=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1313-495x360.jpg\" width=\"495\" height=\"360\"  title='IMG_1313' alt='' \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-5507 avia-img-lazy-loading-5507\"  width=\"640\" height=\"360\" src=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1313.jpg\" title='IMG_1313' alt='' srcset=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1313.jpg 640w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1313-300x169.jpg 300w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1313-450x253.jpg 450w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1313-600x338.jpg 600w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1313-537x302.jpg 537w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/div><\/a><a href=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1316.jpg\" data-srcset=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1316.jpg 640w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1316-300x169.jpg 300w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1316-450x253.jpg 450w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1316-600x338.jpg 600w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1316-537x302.jpg 537w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" data-rel='gallery-1' data-prev-img='https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1316.jpg' class='lightbox ' data-onclick='3' title='IMG_1316'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-5516 avia-img-lazy-loading-not-5516\"   src=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1316-495x360.jpg\" width=\"495\" height=\"360\"  title='IMG_1316' alt='' \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-5516 avia-img-lazy-loading-5516\"  width=\"640\" height=\"360\" src=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1316.jpg\" title='IMG_1316' alt='' srcset=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1316.jpg 640w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1316-300x169.jpg 300w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1316-450x253.jpg 450w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1316-600x338.jpg 600w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1316-537x302.jpg 537w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/div><\/a><a href=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1317.jpg\" data-srcset=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1317.jpg 640w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1317-300x169.jpg 300w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1317-450x253.jpg 450w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1317-600x338.jpg 600w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1317-537x302.jpg 537w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" data-rel='gallery-1' data-prev-img='https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1317.jpg' class='lightbox ' data-onclick='4' title='IMG_1317'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-5519 avia-img-lazy-loading-not-5519\"   src=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1317-495x360.jpg\" width=\"495\" height=\"360\"  title='IMG_1317' alt='' \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-5519 avia-img-lazy-loading-5519\"  width=\"640\" height=\"360\" src=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1317.jpg\" title='IMG_1317' alt='' srcset=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1317.jpg 640w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1317-300x169.jpg 300w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1317-450x253.jpg 450w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1317-600x338.jpg 600w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1317-537x302.jpg 537w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/div><\/a><a href=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2097.jpg\" data-srcset=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2097.jpg 640w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2097-300x169.jpg 300w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2097-450x253.jpg 450w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2097-600x338.jpg 600w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2097-537x302.jpg 537w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" data-rel='gallery-1' data-prev-img='https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2097.jpg' class='first_thumb lightbox ' data-onclick='5' title='IMG_2097'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-5588 avia-img-lazy-loading-not-5588\"   src=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2097-495x360.jpg\" width=\"495\" height=\"360\"  title='IMG_2097' alt='' \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-5588 avia-img-lazy-loading-5588\"  width=\"640\" height=\"360\" src=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2097.jpg\" title='IMG_2097' alt='' srcset=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2097.jpg 640w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2097-300x169.jpg 300w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2097-450x253.jpg 450w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2097-600x338.jpg 600w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2097-537x302.jpg 537w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/div><\/a><a href=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1983.jpg\" data-srcset=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1983.jpg 640w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1983-300x169.jpg 300w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1983-450x253.jpg 450w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1983-600x338.jpg 600w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1983-537x302.jpg 537w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" data-rel='gallery-1' data-prev-img='https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1983.jpg' class='lightbox ' data-onclick='6' title='IMG_1983'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-5561 avia-img-lazy-loading-not-5561\"   src=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1983-495x360.jpg\" width=\"495\" height=\"360\"  title='IMG_1983' alt='' \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-5561 avia-img-lazy-loading-5561\"  width=\"640\" height=\"360\" src=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1983.jpg\" title='IMG_1983' alt='' srcset=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1983.jpg 640w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1983-300x169.jpg 300w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1983-450x253.jpg 450w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1983-600x338.jpg 600w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1983-537x302.jpg 537w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/div><\/a><a href=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2054.jpg\" data-srcset=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2054.jpg 640w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2054-300x225.jpg 300w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2054-450x338.jpg 450w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2054-600x450.jpg 600w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2054-403x302.jpg 403w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" data-rel='gallery-1' data-prev-img='https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2054.jpg' class='lightbox ' data-onclick='7' title='IMG_2054'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-5564 avia-img-lazy-loading-not-5564\"   src=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2054-495x400.jpg\" width=\"495\" height=\"400\"  title='IMG_2054' alt='' \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-5564 avia-img-lazy-loading-5564\"  width=\"640\" height=\"480\" src=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2054.jpg\" title='IMG_2054' alt='' srcset=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2054.jpg 640w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2054-300x225.jpg 300w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2054-450x338.jpg 450w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2054-600x450.jpg 600w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_2054-403x302.jpg 403w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/div><\/a><a href=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1634.jpg\" data-srcset=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1634.jpg 640w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1634-300x169.jpg 300w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1634-450x253.jpg 450w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1634-600x338.jpg 600w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1634-537x302.jpg 537w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" data-rel='gallery-1' data-prev-img='https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1634.jpg' class='lightbox ' data-onclick='8' title='IMG_1634'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-5543 avia-img-lazy-loading-not-5543\"   src=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1634-495x360.jpg\" width=\"495\" height=\"360\"  title='IMG_1634' alt='' \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-5543 avia-img-lazy-loading-5543\"  width=\"640\" height=\"360\" src=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1634.jpg\" title='IMG_1634' alt='' srcset=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1634.jpg 640w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1634-300x169.jpg 300w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1634-450x253.jpg 450w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1634-600x338.jpg 600w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1634-537x302.jpg 537w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/div><\/a><a href=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1633.jpg\" data-srcset=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1633.jpg 460w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1633-240x400.jpg 240w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1633-422x705.jpg 422w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1633-450x751.jpg 450w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1633-181x302.jpg 181w\" data-sizes=\"(max-width: 460px) 100vw, 460px\" data-rel='gallery-1' data-prev-img='https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1633.jpg' class='first_thumb lightbox ' data-onclick='9' title='IMG_1633'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-5540 avia-img-lazy-loading-not-5540\"   src=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1633-460x400.jpg\" width=\"460\" height=\"400\"  title='IMG_1633' alt='' \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-5540 avia-img-lazy-loading-5540\"  width=\"460\" height=\"768\" src=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1633.jpg\" title='IMG_1633' alt='' srcset=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1633.jpg 460w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1633-240x400.jpg 240w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1633-422x705.jpg 422w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1633-450x751.jpg 450w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1633-181x302.jpg 181w\" sizes=\"auto, (max-width: 460px) 100vw, 460px\" \/><\/div><\/a><a href=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1322.jpg\" data-srcset=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1322.jpg 640w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1322-300x169.jpg 300w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1322-450x253.jpg 450w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1322-600x338.jpg 600w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1322-537x302.jpg 537w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" data-rel='gallery-1' data-prev-img='https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1322.jpg' class='lightbox ' data-onclick='10' title='IMG_1322'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-5531 avia-img-lazy-loading-not-5531\"   src=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1322-495x360.jpg\" width=\"495\" height=\"360\"  title='IMG_1322' alt='' \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-5531 avia-img-lazy-loading-5531\"  width=\"640\" height=\"360\" src=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1322.jpg\" title='IMG_1322' alt='' srcset=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1322.jpg 640w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1322-300x169.jpg 300w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1322-450x253.jpg 450w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1322-600x338.jpg 600w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1322-537x302.jpg 537w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/div><\/a><a href=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1630.jpg\" data-srcset=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1630.jpg 640w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1630-300x169.jpg 300w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1630-450x253.jpg 450w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1630-600x338.jpg 600w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1630-537x302.jpg 537w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" data-rel='gallery-1' data-prev-img='https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1630.jpg' class='lightbox ' data-onclick='11' title='IMG_1630'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-5537 avia-img-lazy-loading-not-5537\"   src=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1630-495x360.jpg\" width=\"495\" height=\"360\"  title='IMG_1630' alt='' \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-5537 avia-img-lazy-loading-5537\"  width=\"640\" height=\"360\" src=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1630.jpg\" title='IMG_1630' alt='' srcset=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1630.jpg 640w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1630-300x169.jpg 300w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1630-450x253.jpg 450w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1630-600x338.jpg 600w, https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/IMG_1630-537x302.jpg 537w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/div><\/a><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Gi\u00e1 nell&#8217;autunno 2016 ProNepal ha deliberato di sostenere la ricostruzione di una scuola a Ramechap. Poich\u00e9 successivamente il governo nepalese aveva assicurato il finanziamento diretto della ricostruzione della suola ProNepal , prevvia valutazione congiunta con la nostra referente sig.ra Maya Sherpa , si \u00e9 potuto ritirare dall&#8217;iniziativa. Di consequenza la nostra referente ha individuato un [&hellip;]<\/p>\n","protected":false},"author":1184,"featured_media":5501,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[661,650],"tags":[],"class_list":["post-5591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-generale-it","category-progetti-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuova iniziativa - Ricostruzione di una scuola a Jiri, distretto di Shindupalchok - ProNepal Alto Adige aiuta Nepal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pronepal.org\/it\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuova iniziativa - Ricostruzione di una scuola a Jiri, distretto di Shindupalchok - ProNepal Alto Adige aiuta Nepal\" \/>\n<meta property=\"og:description\" content=\"Gi\u00e1 nell&#8217;autunno 2016 ProNepal ha deliberato di sostenere la ricostruzione di una scuola a Ramechap. Poich\u00e9 successivamente il governo nepalese aveva assicurato il finanziamento diretto della ricostruzione della suola ProNepal , prevvia valutazione congiunta con la nostra referente sig.ra Maya Sherpa , si \u00e9 potuto ritirare dall&#8217;iniziativa. Di consequenza la nostra referente ha individuato un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pronepal.org\/it\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\/\" \/>\n<meta property=\"og:site_name\" content=\"ProNepal Alto Adige aiuta Nepal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pronepal-106272526088964\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-30T06:08:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-12-07T17:07:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5704.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ernst Preyer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Pro_Nepal\" \/>\n<meta name=\"twitter:site\" content=\"@Pro_Nepal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ernst Preyer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.pronepal.org\\\/it\\\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pronepal.org\\\/it\\\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\\\/\"},\"author\":{\"name\":\"Ernst Preyer\",\"@id\":\"https:\\\/\\\/www.pronepal.org\\\/it\\\/#\\\/schema\\\/person\\\/9e75605b85f0836aab6899bddd6764e6\"},\"headline\":\"Nuova iniziativa &#8211; Ricostruzione di una scuola a Jiri, distretto di Shindupalchok\",\"datePublished\":\"2017-08-30T06:08:43+00:00\",\"dateModified\":\"2017-12-07T17:07:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.pronepal.org\\\/it\\\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\\\/\"},\"wordCount\":283,\"image\":{\"@id\":\"https:\\\/\\\/www.pronepal.org\\\/it\\\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pronepal.org\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/CIMG5704.jpg\",\"articleSection\":[\"Attualit\u00e0 su Nepal\",\"Progetti in Nepal\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pronepal.org\\\/it\\\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\\\/\",\"url\":\"https:\\\/\\\/www.pronepal.org\\\/it\\\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\\\/\",\"name\":\"Nuova iniziativa - Ricostruzione di una scuola a Jiri, distretto di Shindupalchok - ProNepal Alto Adige aiuta Nepal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pronepal.org\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pronepal.org\\\/it\\\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pronepal.org\\\/it\\\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pronepal.org\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/CIMG5704.jpg\",\"datePublished\":\"2017-08-30T06:08:43+00:00\",\"dateModified\":\"2017-12-07T17:07:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.pronepal.org\\\/it\\\/#\\\/schema\\\/person\\\/9e75605b85f0836aab6899bddd6764e6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pronepal.org\\\/it\\\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pronepal.org\\\/it\\\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.pronepal.org\\\/it\\\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.pronepal.org\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/CIMG5704.jpg\",\"contentUrl\":\"https:\\\/\\\/www.pronepal.org\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/CIMG5704.jpg\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pronepal.org\\\/it\\\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.pronepal.org\\\/it\\\/pronepal-alto-adige-aiutare-nepal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuova iniziativa &#8211; Ricostruzione di una scuola a Jiri, distretto di Shindupalchok\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pronepal.org\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.pronepal.org\\\/it\\\/\",\"name\":\"ProNepal Alto Adige aiuta Nepal\",\"description\":\"Aiuto per Nepal - Societ\u00e0 senza scopi di lucro - Sostegno di diversi progetti in Nepal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pronepal.org\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pronepal.org\\\/it\\\/#\\\/schema\\\/person\\\/9e75605b85f0836aab6899bddd6764e6\",\"name\":\"Ernst Preyer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5196bdc70ad24e266145187c9766321f53123800abb11711dad038483950548d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5196bdc70ad24e266145187c9766321f53123800abb11711dad038483950548d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5196bdc70ad24e266145187c9766321f53123800abb11711dad038483950548d?s=96&d=mm&r=g\",\"caption\":\"Ernst Preyer\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuova iniziativa - Ricostruzione di una scuola a Jiri, distretto di Shindupalchok - ProNepal Alto Adige aiuta Nepal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pronepal.org\/it\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\/","og_locale":"it_IT","og_type":"article","og_title":"Nuova iniziativa - Ricostruzione di una scuola a Jiri, distretto di Shindupalchok - ProNepal Alto Adige aiuta Nepal","og_description":"Gi\u00e1 nell&#8217;autunno 2016 ProNepal ha deliberato di sostenere la ricostruzione di una scuola a Ramechap. Poich\u00e9 successivamente il governo nepalese aveva assicurato il finanziamento diretto della ricostruzione della suola ProNepal , prevvia valutazione congiunta con la nostra referente sig.ra Maya Sherpa , si \u00e9 potuto ritirare dall&#8217;iniziativa. Di consequenza la nostra referente ha individuato un [&hellip;]","og_url":"https:\/\/www.pronepal.org\/it\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\/","og_site_name":"ProNepal Alto Adige aiuta Nepal","article_publisher":"https:\/\/www.facebook.com\/pronepal-106272526088964\/","article_published_time":"2017-08-30T06:08:43+00:00","article_modified_time":"2017-12-07T17:07:00+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5704.jpg","type":"image\/jpeg"}],"author":"Ernst Preyer","twitter_card":"summary_large_image","twitter_creator":"@Pro_Nepal","twitter_site":"@Pro_Nepal","twitter_misc":{"Written by":"Ernst Preyer","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pronepal.org\/it\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\/#article","isPartOf":{"@id":"https:\/\/www.pronepal.org\/it\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\/"},"author":{"name":"Ernst Preyer","@id":"https:\/\/www.pronepal.org\/it\/#\/schema\/person\/9e75605b85f0836aab6899bddd6764e6"},"headline":"Nuova iniziativa &#8211; Ricostruzione di una scuola a Jiri, distretto di Shindupalchok","datePublished":"2017-08-30T06:08:43+00:00","dateModified":"2017-12-07T17:07:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pronepal.org\/it\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\/"},"wordCount":283,"image":{"@id":"https:\/\/www.pronepal.org\/it\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5704.jpg","articleSection":["Attualit\u00e0 su Nepal","Progetti in Nepal"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.pronepal.org\/it\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\/","url":"https:\/\/www.pronepal.org\/it\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\/","name":"Nuova iniziativa - Ricostruzione di una scuola a Jiri, distretto di Shindupalchok - ProNepal Alto Adige aiuta Nepal","isPartOf":{"@id":"https:\/\/www.pronepal.org\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pronepal.org\/it\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\/#primaryimage"},"image":{"@id":"https:\/\/www.pronepal.org\/it\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5704.jpg","datePublished":"2017-08-30T06:08:43+00:00","dateModified":"2017-12-07T17:07:00+00:00","author":{"@id":"https:\/\/www.pronepal.org\/it\/#\/schema\/person\/9e75605b85f0836aab6899bddd6764e6"},"breadcrumb":{"@id":"https:\/\/www.pronepal.org\/it\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pronepal.org\/it\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.pronepal.org\/it\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\/#primaryimage","url":"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5704.jpg","contentUrl":"https:\/\/www.pronepal.org\/wp-content\/uploads\/2017\/08\/CIMG5704.jpg","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.pronepal.org\/it\/nuova-iniziativa-ricostruzione-di-una-scuola-a-jiri-distretto-di-shindupalchok\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.pronepal.org\/it\/pronepal-alto-adige-aiutare-nepal\/"},{"@type":"ListItem","position":2,"name":"Nuova iniziativa &#8211; Ricostruzione di una scuola a Jiri, distretto di Shindupalchok"}]},{"@type":"WebSite","@id":"https:\/\/www.pronepal.org\/it\/#website","url":"https:\/\/www.pronepal.org\/it\/","name":"ProNepal Alto Adige aiuta Nepal","description":"Aiuto per Nepal - Societ\u00e0 senza scopi di lucro - Sostegno di diversi progetti in Nepal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pronepal.org\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.pronepal.org\/it\/#\/schema\/person\/9e75605b85f0836aab6899bddd6764e6","name":"Ernst Preyer","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/5196bdc70ad24e266145187c9766321f53123800abb11711dad038483950548d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5196bdc70ad24e266145187c9766321f53123800abb11711dad038483950548d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5196bdc70ad24e266145187c9766321f53123800abb11711dad038483950548d?s=96&d=mm&r=g","caption":"Ernst Preyer"}}]}},"_links":{"self":[{"href":"https:\/\/www.pronepal.org\/it\/wp-json\/wp\/v2\/posts\/5591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pronepal.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pronepal.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pronepal.org\/it\/wp-json\/wp\/v2\/users\/1184"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pronepal.org\/it\/wp-json\/wp\/v2\/comments?post=5591"}],"version-history":[{"count":0,"href":"https:\/\/www.pronepal.org\/it\/wp-json\/wp\/v2\/posts\/5591\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pronepal.org\/it\/wp-json\/wp\/v2\/media\/5501"}],"wp:attachment":[{"href":"https:\/\/www.pronepal.org\/it\/wp-json\/wp\/v2\/media?parent=5591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pronepal.org\/it\/wp-json\/wp\/v2\/categories?post=5591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pronepal.org\/it\/wp-json\/wp\/v2\/tags?post=5591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}